<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>21</b><br />
<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>26</b><br />
<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>28</b><br />
<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>36</b><br />
<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>38</b><br />
<br />
<b>Warning</b>:  Attempt to read property "object_type" on bool in <b>/var/www/clients/client2/web3/web/wp-content/plugins/wordpress-seo/src/helpers/permalink-helper.php</b> on line <b>40</b><br />
{"id":223,"date":"2022-12-16T14:24:22","date_gmt":"2022-12-16T19:24:22","guid":{"rendered":"https:\/\/amerispa.codepoet.ca\/estrimont-suites-spa\/?page_id=223"},"modified":"2024-02-09T16:01:34","modified_gmt":"2024-02-09T21:01:34","slug":"soins-du-visage","status":"publish","type":"page","link":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/","title":{"rendered":"Soins du visage"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":162,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-typedesoin.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-223","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin  - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Soins du visage - Amerispa Estrimont Suites &amp; Spa<\/title>\n<meta name=\"description\" content=\"Offrez \u00e0 votre visage l&#039;attention qu&#039;il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soins du visage\" \/>\n<meta property=\"og:description\" content=\"Offrez \u00e0 votre visage l&#039;attention qu&#039;il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/\" \/>\n<meta property=\"og:site_name\" content=\"Estrimont\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T21:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/\",\"url\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/\",\"name\":\"Soins du visage - Amerispa Estrimont Suites & Spa\",\"isPartOf\":{\"@id\":\"\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg\",\"datePublished\":\"2022-12-16T19:24:22+00:00\",\"dateModified\":\"2024-02-09T21:01:34+00:00\",\"description\":\"Offrez \u00e0 votre visage l'attention qu'il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.\",\"breadcrumb\":{\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage\",\"url\":\"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg\",\"contentUrl\":\"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/amerispadev.ca\/estrimont\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soins du visage\"}]},{\"@type\":\"WebSite\",\"@id\":\"\/#website\",\"url\":\"\/\",\"name\":\"Estrimont\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Soins du visage - Amerispa Estrimont Suites & Spa","description":"Offrez \u00e0 votre visage l'attention qu'il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/","og_locale":"en_US","og_type":"article","og_title":"Soins du visage","og_description":"Offrez \u00e0 votre visage l'attention qu'il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.","og_url":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/","og_site_name":"Estrimont","article_modified_time":"2024-02-09T21:01:34+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/","url":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/","name":"Soins du visage - Amerispa Estrimont Suites & Spa","isPartOf":{"@id":"\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage"},"image":{"@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage"},"thumbnailUrl":"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg","datePublished":"2022-12-16T19:24:22+00:00","dateModified":"2024-02-09T21:01:34+00:00","description":"Offrez \u00e0 votre visage l'attention qu'il m\u00e9rite. D\u00e9couvrez notre gamme de soins du visage, con\u00e7us pour r\u00e9pondre aux besoins de tous les types de peau.","breadcrumb":{"@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#primaryimage","url":"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg","contentUrl":"https:\/\/amerispadev.ca\/estrimont\/wp-content\/uploads\/sites\/13\/2022\/12\/amerispa_DSC2276_switch.jpg","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/amerispadev.ca\/estrimont\/soins-du-visage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/amerispadev.ca\/estrimont\/"},{"@type":"ListItem","position":2,"name":"Soins du visage"}]},{"@type":"WebSite","@id":"\/#website","url":"\/","name":"Estrimont","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/pages\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":4,"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/pages\/223\/revisions"}],"predecessor-version":[{"id":475,"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/pages\/223\/revisions\/475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/media\/162"}],"wp:attachment":[{"href":"https:\/\/amerispadev.ca\/estrimont\/wp-json\/wp\/v2\/media?parent=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}