{"id":336,"date":"2022-12-17T14:27:02","date_gmt":"2022-12-17T19:27:02","guid":{"rendered":"https:\/\/amerispa.codepoet.ca\/hilton-lac-leamy\/?page_id=336"},"modified":"2024-02-09T15:46:25","modified_gmt":"2024-02-09T20:46:25","slug":"massages","status":"publish","type":"page","link":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/","title":{"rendered":"Massages"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":188,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-typedesoin.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-336","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin  - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Massages - Amerispa Hilton Lac-Leamy<\/title>\n<meta name=\"description\" content=\"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massages\" \/>\n<meta property=\"og:description\" content=\"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/\" \/>\n<meta property=\"og:site_name\" content=\"Hilton Lac-Leamy\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T20:46:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/\",\"url\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/\",\"name\":\"Massages - Amerispa Hilton Lac-Leamy\",\"isPartOf\":{\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg\",\"datePublished\":\"2022-12-17T19:27:02+00:00\",\"dateModified\":\"2024-02-09T20:46:25+00:00\",\"description\":\"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.\",\"breadcrumb\":{\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage\",\"url\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg\",\"contentUrl\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/#website\",\"url\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/\",\"name\":\"Hilton Lac-Leamy\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/amerispadev.ca\/hilton-lac-leamy\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Massages - Amerispa Hilton Lac-Leamy","description":"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/","og_locale":"en_US","og_type":"article","og_title":"Massages","og_description":"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.","og_url":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/","og_site_name":"Hilton Lac-Leamy","article_modified_time":"2024-02-09T20:46:25+00:00","og_image":[{"width":1920,"height":1281,"url":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/","url":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/","name":"Massages - Amerispa Hilton Lac-Leamy","isPartOf":{"@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage"},"image":{"@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage"},"thumbnailUrl":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg","datePublished":"2022-12-17T19:27:02+00:00","dateModified":"2024-02-09T20:46:25+00:00","description":"Discover our range of classic and signature massages. Relax and rejuvenate with our professional therapists.","breadcrumb":{"@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#primaryimage","url":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg","contentUrl":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-content\/uploads\/sites\/10\/2022\/12\/3_DSC8288.jpg","width":1920,"height":1281},{"@type":"BreadcrumbList","@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/en\/massages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/"},{"@type":"ListItem","position":2,"name":"Massages"}]},{"@type":"WebSite","@id":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/#website","url":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/","name":"Hilton Lac-Leamy","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/pages\/336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/comments?post=336"}],"version-history":[{"count":4,"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/pages\/336\/revisions"}],"predecessor-version":[{"id":505,"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/pages\/336\/revisions\/505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/media\/188"}],"wp:attachment":[{"href":"https:\/\/amerispadev.ca\/hilton-lac-leamy\/wp-json\/wp\/v2\/media?parent=336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}